{"id":465,"count":3,"description":"","link":"http:\/\/www.codethisfor.me\/redwood\/category\/exterior-wood-finishing\/","name":"Exterior Wood Finishing","slug":"exterior-wood-finishing","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.4.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Exterior Wood Finishing Archives - Redwood UK<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exterior Wood Finishing Archives - Redwood UK\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.codethisfor.me\/redwood\/category\/exterior-wood-finishing\/\" \/>\n<meta property=\"og:site_name\" content=\"Redwood UK\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.codethisfor.me\/redwood\/#website\",\"url\":\"http:\/\/www.codethisfor.me\/redwood\/\",\"name\":\"Redwood UK\",\"description\":\"Redwood Innovations\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/www.codethisfor.me\/redwood\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"CollectionPage\",\"@id\":\"http:\/\/www.codethisfor.me\/redwood\/category\/exterior-wood-finishing\/#webpage\",\"url\":\"http:\/\/www.codethisfor.me\/redwood\/category\/exterior-wood-finishing\/\",\"name\":\"Exterior Wood Finishing Archives - Redwood UK\",\"isPartOf\":{\"@id\":\"http:\/\/www.codethisfor.me\/redwood\/#website\"},\"breadcrumb\":{\"@id\":\"http:\/\/www.codethisfor.me\/redwood\/category\/exterior-wood-finishing\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.codethisfor.me\/redwood\/category\/exterior-wood-finishing\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.codethisfor.me\/redwood\/category\/exterior-wood-finishing\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/www.codethisfor.me\/redwood\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exterior Wood Finishing\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exterior Wood Finishing Archives - Redwood UK","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_GB","og_type":"article","og_title":"Exterior Wood Finishing Archives - Redwood UK","og_url":"http:\/\/www.codethisfor.me\/redwood\/category\/exterior-wood-finishing\/","og_site_name":"Redwood UK","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/www.codethisfor.me\/redwood\/#website","url":"http:\/\/www.codethisfor.me\/redwood\/","name":"Redwood UK","description":"Redwood Innovations","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.codethisfor.me\/redwood\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"},{"@type":"CollectionPage","@id":"http:\/\/www.codethisfor.me\/redwood\/category\/exterior-wood-finishing\/#webpage","url":"http:\/\/www.codethisfor.me\/redwood\/category\/exterior-wood-finishing\/","name":"Exterior Wood Finishing Archives - Redwood UK","isPartOf":{"@id":"http:\/\/www.codethisfor.me\/redwood\/#website"},"breadcrumb":{"@id":"http:\/\/www.codethisfor.me\/redwood\/category\/exterior-wood-finishing\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.codethisfor.me\/redwood\/category\/exterior-wood-finishing\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.codethisfor.me\/redwood\/category\/exterior-wood-finishing\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/www.codethisfor.me\/redwood\/"},{"@type":"ListItem","position":2,"name":"Exterior Wood Finishing"}]}]}},"acf":[],"_links":{"self":[{"href":"http:\/\/www.codethisfor.me\/redwood\/wp-json\/wp\/v2\/categories\/465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.codethisfor.me\/redwood\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/www.codethisfor.me\/redwood\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/www.codethisfor.me\/redwood\/wp-json\/wp\/v2\/posts?categories=465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}